{"id":3681,"date":"2022-12-05T22:33:57","date_gmt":"2022-12-06T01:33:57","guid":{"rendered":"https:\/\/tenhosaude.com\/?p=3681"},"modified":"2024-08-20T22:51:14","modified_gmt":"2024-08-21T01:51:14","slug":"8-tipos-de-insonia-como-identificar-e-solucoes","status":"publish","type":"post","link":"https:\/\/tenhosaude.com\/en\/8-types-of-insomnia-how-to-identify-and-solutions\/","title":{"rendered":"Can&#039;t sleep? Discover 8 types of insomnia: how to identify and what are the solutions."},"content":{"rendered":"<p class=\"wp-block-paragraph\">It\u2019s quite common for people to say that \u201cit\u2019s nothing\u201d without a quality night\u2019s sleep. Lack of productivity, tiredness, irritability, not being able to concentrate and headache are some of the signs faced due to a \u201cpoor sleep\u201d night.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Before identifying your type of insomnia, it is important to understand that there are two motivators, they are:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Internal factors (primary):<\/strong> It is caused by the organism itself, that is, it exists independently of any other condition, such as the body&#039;s difficulty in producing melatonin, known as the \u201csleep hormone\u201d. It needs treatment to be resolved.<br><br><strong>External factors (secondary):<\/strong> It is caused by external factors and conditions, for example, the consumption of caffeine before bed, emotional upset due to anxiety or stress, the environment where you sleep, habits and other situations.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Generally, insomnia caused by external factors is resolved as soon as the reason for this condition is resolved.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Knowing the two types of factors, the time has come to define which type you may have.<\/p>\n\n\n\n<h2 id=\"insonia-geral-habitos\" class=\"wp-block-heading\">General insomnia (habits):<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"1024\"  height=\"576\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAABAAAAAJAAQMAAAApW4aWAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAF5JREFUeNrtwQEBAAAAgiD\/r25IQAEAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAO8GIk8AAbOpTZoAAAAASUVORK5CYII=\"  alt=\"General Insomnia Habits\"  class=\"wp-image-3688 pk-lazyload\"  title=\"-\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"  data-pk-src=\"https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-geral-Habitos-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1024x576.jpg\"  data-pk-srcset=\"https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-geral-Habitos-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1024x576.jpg 1024w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-geral-Habitos-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-300x169.jpg 300w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-geral-Habitos-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-768x432.jpg 768w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-geral-Habitos-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1536x864.jpg 1536w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-geral-Habitos-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-380x214.jpg 380w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-geral-Habitos-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-800x450.jpg 800w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-geral-Habitos-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1160x653.jpg 1160w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-geral-Habitos-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-80x46.jpg 80w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-geral-Habitos-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-150x84.jpg 150w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-geral-Habitos-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-760x428.jpg 760w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-geral-Habitos-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1600x900.jpg 1600w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-geral-Habitos-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-600x338.jpg 600w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-geral-Habitos-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude.jpg 1920w\" ><figcaption class=\"wp-element-caption\">Being exposed to light before bed harms your sleep | Image from Freepik<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">It is the most common of all, being a type of sleep disorder in which there is <strong>difficulty falling asleep, waking up during the night, or waking up too early<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">They may be motivated by <strong>bad habits<\/strong> of sleep close to bedtime, such as:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Being exposed to light, such as lamps in the room, cell phones, TVs and computers.<\/li>\n\n\n\n<li>Practice physical exercise hours before bed.<\/li>\n\n\n\n<li>Change your bedtime frequently.<\/li>\n\n\n\n<li>Eating foods considered \u201cheavy\u201d.<\/li>\n\n\n\n<li>Studying, working or carrying out a task that requires a lot of brain activity.<\/li>\n\n\n\n<li>Nap after 3pm.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">People who identify with these symptoms should analyze what they are doing before bed, and identify whether some of these habits are making it difficult to sleep. After identifying and eliminating it, sleep will return to normal.<\/p>\n\n\n\n<h2 id=\"insonia-aguda-emocional\" class=\"wp-block-heading\">Acute (emotional) insomnia:<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"1024\"  height=\"576\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAABAAAAAJAAQMAAAApW4aWAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAF5JREFUeNrtwQEBAAAAgiD\/r25IQAEAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAO8GIk8AAbOpTZoAAAAASUVORK5CYII=\"  alt=\"Acute emotional insomnia.\"  class=\"wp-image-3684 pk-lazyload\"  title=\"-\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"  data-pk-src=\"https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-aguda-emocional-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1024x576.jpg\"  data-pk-srcset=\"https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-aguda-emocional-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1024x576.jpg 1024w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-aguda-emocional-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-300x169.jpg 300w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-aguda-emocional-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-768x432.jpg 768w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-aguda-emocional-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1536x864.jpg 1536w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-aguda-emocional-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-380x214.jpg 380w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-aguda-emocional-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-800x450.jpg 800w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-aguda-emocional-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1160x653.jpg 1160w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-aguda-emocional-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-80x46.jpg 80w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-aguda-emocional-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-150x84.jpg 150w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-aguda-emocional-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-760x428.jpg 760w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-aguda-emocional-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1600x900.jpg 1600w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-aguda-emocional-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-600x338.jpg 600w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-aguda-emocional-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude.jpg 1920w\" ><figcaption class=\"wp-element-caption\">Lack of sleep due to stress | Image by Freepik<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">This type, also known as adjustment insomnia, occurs for specific reasons. <strong>emotional stress<\/strong>, such as a separation, bereavement, job loss and others.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In these cases, it will last for a short period until the problem that causes the lack of sleep is resolved. Generally the duration\u00b9 is a few weeks, and can vary by up to three months, depending on the <em>American Academy of Sleep Medicine<\/em>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">This type requires attention, as maintaining this condition for a period longer than 3 months can turn into permanent or chronic insomnia. Look for a specialist if this is your case.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">This problem that affects sleep is resolved when what causes stress ends or when you get used to what causes stress.<\/p>\n\n\n\n<h2 id=\"insonia-gerada-por-substancias-alimentacao\" class=\"wp-block-heading\">Insomnia generated by substances (food):<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"1024\"  height=\"576\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAABAAAAAJAAQMAAAApW4aWAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAF5JREFUeNrtwQEBAAAAgiD\/r25IQAEAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAO8GIk8AAbOpTZoAAAAASUVORK5CYII=\"  alt=\"Insomnia generated by substances\"  class=\"wp-image-3687 pk-lazyload\"  title=\"-\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"  data-pk-src=\"https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-substancias-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1024x576.jpg\"  data-pk-srcset=\"https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-substancias-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1024x576.jpg 1024w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-substancias-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-300x169.jpg 300w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-substancias-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-768x432.jpg 768w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-substancias-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1536x864.jpg 1536w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-substancias-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-380x214.jpg 380w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-substancias-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-800x450.jpg 800w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-substancias-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1160x653.jpg 1160w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-substancias-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-80x46.jpg 80w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-substancias-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-150x84.jpg 150w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-substancias-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-760x428.jpg 760w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-substancias-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1600x900.jpg 1600w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-substancias-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-600x338.jpg 600w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-substancias-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude.jpg 1920w\" ><figcaption class=\"wp-element-caption\">Eating a lot before bed disrupts sleep | Image by master1305 on Freepik<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">This category of external factor is caused when the <strong>lack of sleep is linked to the use of certain drinks, foods and medicines<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Is everything fine with your body and there is no psychological problem and yet you still have difficulty sleeping? The cause may be generated by something you are consuming.<br><br>Some examples are products that contain caffeine, such as energy drinks, coffee, some teas; and other substances such as alcohol and even supplements such as pre-workouts.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Certain types of medicines that treat blood pressure, diabetes and depression can cause insomnia, in these cases it is recommended to see a doctor and indicate the difficulty in sleeping due to the use of the medicine.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">People who have identified themselves with these symptoms should analyze what they are consuming a few hours of sleep, and identify whether any of these foods contain something that is speeding up their body and keeping sleep away.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">After identifying and eliminating consumption, sleep tends to normalize.<\/p>\n\n\n\n<h2 id=\"insonia-psicofisiologica\" class=\"wp-block-heading\">Psychophysiological insomnia:<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"1024\"  height=\"576\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAABAAAAAJAAQMAAAApW4aWAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAF5JREFUeNrtwQEBAAAAgiD\/r25IQAEAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAO8GIk8AAbOpTZoAAAAASUVORK5CYII=\"  alt=\"Psychophysiological insomnia\"  class=\"wp-image-3691 pk-lazyload\"  title=\"-\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"  data-pk-src=\"https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-psicofisiologica-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1024x576.jpg\"  data-pk-srcset=\"https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-psicofisiologica-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1024x576.jpg 1024w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-psicofisiologica-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-300x169.jpg 300w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-psicofisiologica-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-768x432.jpg 768w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-psicofisiologica-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1536x864.jpg 1536w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-psicofisiologica-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-380x214.jpg 380w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-psicofisiologica-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-800x450.jpg 800w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-psicofisiologica-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1160x653.jpg 1160w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-psicofisiologica-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-80x46.jpg 80w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-psicofisiologica-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-150x84.jpg 150w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-psicofisiologica-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-760x428.jpg 760w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-psicofisiologica-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1600x900.jpg 1600w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-psicofisiologica-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-600x338.jpg 600w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-psicofisiologica-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude.jpg 1920w\" ><figcaption class=\"wp-element-caption\">Anxiety generated by difficulty sleeping | Image by Freepik<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">This class is associated with <strong>high anxiety that refers to psychological concern about not being able to sleep<\/strong>. Because when lying in bed, they tend to have a great flow of mental activity instead of relaxing. Generating anxiety and stress.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">People affected by this type feel increasingly anxious and tense as the time to fall asleep approaches, <strong>generating a kind of panic about sleeping and they generally associate sleep with something negative<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Some people with this condition are only able to normalize after changing their environment, as they have associated their own room and bed as an anxiety trigger.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">According to a study\u00b2 by <em>Scientific Reports<\/em>, the best treatment for this psychophysiological class is<strong> <\/strong>cognitive behavioral therapy for insomnia known as CBT-I.<\/p>\n\n\n\n<h2 id=\"insonia-paradoxal\" class=\"wp-block-heading\">Paradoxical insomnia:<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"1024\"  height=\"576\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAABAAAAAJAAQMAAAApW4aWAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAF5JREFUeNrtwQEBAAAAgiD\/r25IQAEAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAO8GIk8AAbOpTZoAAAAASUVORK5CYII=\"  alt=\"Paradoxical insomnia\"  class=\"wp-image-3690 pk-lazyload\"  title=\"-\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"  data-pk-src=\"https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-paradoxal-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1024x576.jpg\"  data-pk-srcset=\"https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-paradoxal-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1024x576.jpg 1024w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-paradoxal-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-300x169.jpg 300w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-paradoxal-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-768x432.jpg 768w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-paradoxal-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1536x864.jpg 1536w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-paradoxal-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-380x214.jpg 380w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-paradoxal-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-800x450.jpg 800w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-paradoxal-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1160x653.jpg 1160w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-paradoxal-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-80x46.jpg 80w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-paradoxal-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-150x84.jpg 150w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-paradoxal-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-760x428.jpg 760w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-paradoxal-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1600x900.jpg 1600w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-paradoxal-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-600x338.jpg 600w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-paradoxal-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude.jpg 1920w\" ><figcaption class=\"wp-element-caption\">Feeling of lack of sleep | Image by tirachardz on Freepik<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">This type of internal factor insomnia, also known as sleep hypochondria, is motivated by a <strong>false feeling of not being able to sleep<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The unusual thing is that the person affected by this class can actually fall asleep relatively quickly and with a good quality of sleep. According\u00b3 to <em>Frontiers in Psychiatry<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">This conclusion was made in a study, where people who reported not being able to sleep well or for a short period of time were subjected to polysomnography exams, which analyze sleep data.<br><br>One group of people really couldn&#039;t sleep well, but another group, <strong>They managed to get quality sleep and fall asleep quickly, but they reported the feeling of having taken a long time to fall asleep and having slept for very few hours<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">This occurs because for this group of people, the brain is in a state of alert while the body sleeps. That&#039;s why they report being conscious throughout the night, as if they were awake.<\/p>\n\n\n\n<h2 id=\"insonia-gerada-por-condicoes-medicas\" class=\"wp-block-heading\">Insomnia generated by medical conditions:<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"1024\"  height=\"576\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAABAAAAAJAAQMAAAApW4aWAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAF5JREFUeNrtwQEBAAAAgiD\/r25IQAEAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAO8GIk8AAbOpTZoAAAAASUVORK5CYII=\"  alt=\"Insomnia generated by medical conditions\"  class=\"wp-image-3686 pk-lazyload\"  title=\"-\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"  data-pk-src=\"https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-condicoes-medicas-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1024x576.jpg\"  data-pk-srcset=\"https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-condicoes-medicas-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1024x576.jpg 1024w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-condicoes-medicas-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-300x169.jpg 300w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-condicoes-medicas-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-768x432.jpg 768w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-condicoes-medicas-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1536x864.jpg 1536w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-condicoes-medicas-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-380x214.jpg 380w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-condicoes-medicas-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-800x450.jpg 800w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-condicoes-medicas-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1160x653.jpg 1160w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-condicoes-medicas-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-80x46.jpg 80w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-condicoes-medicas-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-150x84.jpg 150w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-condicoes-medicas-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-760x428.jpg 760w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-condicoes-medicas-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1600x900.jpg 1600w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-condicoes-medicas-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-600x338.jpg 600w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-gerada-por-condicoes-medicas-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude.jpg 1920w\" ><figcaption class=\"wp-element-caption\">Insomnia due to problems and illnesses | Image by Drazen Zigic on Freepik<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">This external factor insomnia is motivated by problems linked to some physical or mental problem, where insomnia is a symptom and not the cause.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Some examples are gastrointestinal problems, headaches, thyroid pain, chronic pain, cancer and neurodegenerative diseases such as Alzheimer&#039;s and Parkinson&#039;s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In these cases, after solving the problem or treating the disease that causes insomnia, sleep will return to normal.<\/p>\n\n\n\n<h2 id=\"insonia-de-comportamentos-infantis\" class=\"wp-block-heading\">Childhood Behaviors Insomnia:<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"1024\"  height=\"576\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAABAAAAAJAAQMAAAApW4aWAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAF5JREFUeNrtwQEBAAAAgiD\/r25IQAEAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAO8GIk8AAbOpTZoAAAAASUVORK5CYII=\"  alt=\"Childhood Behaviors Insomnia\"  class=\"wp-image-3685 pk-lazyload\"  title=\"-\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"  data-pk-src=\"https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-de-comportamento-infantis-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1024x576.jpg\"  data-pk-srcset=\"https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-de-comportamento-infantis-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1024x576.jpg 1024w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-de-comportamento-infantis-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-300x169.jpg 300w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-de-comportamento-infantis-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-768x432.jpg 768w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-de-comportamento-infantis-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1536x864.jpg 1536w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-de-comportamento-infantis-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-380x214.jpg 380w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-de-comportamento-infantis-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-800x450.jpg 800w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-de-comportamento-infantis-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1160x653.jpg 1160w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-de-comportamento-infantis-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-80x46.jpg 80w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-de-comportamento-infantis-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-150x84.jpg 150w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-de-comportamento-infantis-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-760x428.jpg 760w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-de-comportamento-infantis-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1600x900.jpg 1600w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-de-comportamento-infantis-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-600x338.jpg 600w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-de-comportamento-infantis-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude.jpg 1920w\" ><figcaption class=\"wp-element-caption\">Dependence on parents for sleep | Image by Freepik<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">It is normal that as children grow, the way they sleep also changes completely.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">These changes are also known as BIC (Behavioral Insomnia of Childhood), on average, this disorder can affect around 30% of children.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Second<sup>4<\/sup> The <em>American Thoracic Society<\/em>, there are three subtypes of this insomnia:&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1- <strong>Associated with falling asleep:<\/strong> refers to difficulty falling asleep. Some examples include the child only being able to sleep in the presence of their parents, or depending on a favorite toy or blanket.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2- <strong>Sleep Procrastination:<\/strong> occurs when the child refuses to sleep, usually making some kind of \u201ctantrum\u201d, asking to go to the bathroom or saying he is hungry; in order to delay bedtime.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3-<strong> Mixed:<\/strong> occurs when the other two behaviors are practiced together.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A child professional should be sought to treat these behaviors if your child has any of these habits.<\/p>\n\n\n\n<h2 id=\"insonia-nao-identificada\" class=\"wp-block-heading\">Unidentified insomnia:<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img  loading=\"lazy\"  decoding=\"async\"  width=\"1024\"  height=\"576\"  src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAABAAAAAJAAQMAAAApW4aWAAAAA1BMVEUAAP+KeNJXAAAAAXRSTlMAQObYZgAAAAlwSFlzAAAOxAAADsQBlSsOGwAAAF5JREFUeNrtwQEBAAAAgiD\/r25IQAEAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAO8GIk8AAbOpTZoAAAAASUVORK5CYII=\"  alt=\"Unidentified insomnia\"  class=\"wp-image-3689 pk-lazyload\"  title=\"-\"  data-pk-sizes=\"auto\"  data-ls-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"  data-pk-src=\"https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-nao-identificada-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1024x576.jpg\"  data-pk-srcset=\"https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-nao-identificada-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1024x576.jpg 1024w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-nao-identificada-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-300x169.jpg 300w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-nao-identificada-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-768x432.jpg 768w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-nao-identificada-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1536x864.jpg 1536w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-nao-identificada-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-380x214.jpg 380w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-nao-identificada-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-800x450.jpg 800w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-nao-identificada-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1160x653.jpg 1160w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-nao-identificada-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-80x46.jpg 80w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-nao-identificada-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-150x84.jpg 150w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-nao-identificada-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-760x428.jpg 760w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-nao-identificada-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-1600x900.jpg 1600w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-nao-identificada-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude-600x338.jpg 600w, https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/Insonia-nao-identificada-8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude.jpg 1920w\" ><figcaption class=\"wp-element-caption\">Difficulties in identifying the cause of insomnia | Image by Freepik<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Some professionals may classify their patients with this type of insomnia, also known as \u201cunspecified\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">It occurs when the cause of the lack of sleep has not yet been identified, where the patient will undergo further evaluations, being considered a type of temporary classification.<\/p>\n\n\n\n<div class=\"cnvs-block-collapsibles cnvs-block-collapsibles-1670288202483 cnvs-block-collapsibles-2\" >\n\t\n<div class=\"cnvs-block-collapsible cnvs-block-collapsible-1670288202638\" >\n\t<div class=\"cnvs-block-collapsible-title\">\n\t\t<h6 id=\"referencias-biograficas-estudos\" class=\"cnvs-block-collapsible-heading\">\n\t\t\t<a href=\"#\">Biographical references (studies):<\/a>\n\t\t<\/h6>\n\t<\/div>\n\t<div class=\"cnvs-block-collapsible-content\">\n\t\t\n\n<p class=\"wp-block-paragraph\">Here are all the scientific studies we used to write this article, to access, just click on the title:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1 &#8211; <em><span style=\"text-decoration: underline;\"><a href=\"https:\/\/aasm.org\/resources\/factsheets\/insomnia.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">American Academy of Sleep Medicine<\/a><\/span><\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2- <span style=\"text-decoration: underline;\"><em><a href=\"https:\/\/www.nature.com\/articles\/s41598-017-13065-0\" target=\"_blank\" rel=\"noreferrer noopener\">Exploration of changes in brain response to sleep-related imagery following cognitive behavioral therapy for psychophysiological insomnia.<\/a><\/em><\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3- <em><span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC8139557\/\" target=\"_blank\" rel=\"noreferrer noopener\">Alterations of subcortical brain structures in paradoxical and psychophysiological insomnia disorder.<\/a><\/span><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4- <em><span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.atsjournals.org\/doi\/pdf\/10.1164\/rccm.2038P20\" target=\"_blank\" rel=\"noreferrer noopener\">Childhood behavioral insomnia.<\/a><\/span><\/em><\/p>\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"cnvs-block-collapsible cnvs-block-collapsible-1670291527567\" >\n\t<div class=\"cnvs-block-collapsible-title\">\n\t\t<h6 id=\"\" class=\"cnvs-block-collapsible-heading\">\n\t\t\t<a href=\"#\"><\/a>\n\t\t<\/h6>\n\t<\/div>\n\t<div class=\"cnvs-block-collapsible-content\">\n\t\t\t<\/div>\n<\/div>\n\n<\/div>\n\n\n\n<h2 id=\"-2\" class=\"wp-block-heading\"> <\/h2>","protected":false},"excerpt":{"rendered":"If you are having trouble falling asleep, these 8 types of insomnia could be the reason. Understanding them is the first step to solving them and getting back to sleeping well. Check out:","protected":false},"author":1,"featured_media":3683,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_post_was_ever_published":false},"categories":[354],"tags":[170,171,150,169],"class_list":["post-3681","post","type-post","status-publish","format-standard","has-post-thumbnail","category-saude-mental","tag-dormir","tag-habitos","tag-insonia","tag-sono","cs-entry","cs-video-wrap"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":false,"jetpack_featured_media_url":"https:\/\/tenhosaude.com\/wp-content\/uploads\/2022\/12\/8-tipos-de-insonia-o-que-saber-como-identificar-e-quais-as-solucoes-Tenho-Saude.jpg","_links":{"self":[{"href":"https:\/\/tenhosaude.com\/en\/wp-json\/wp\/v2\/posts\/3681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tenhosaude.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tenhosaude.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tenhosaude.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tenhosaude.com\/en\/wp-json\/wp\/v2\/comments?post=3681"}],"version-history":[{"count":1,"href":"https:\/\/tenhosaude.com\/en\/wp-json\/wp\/v2\/posts\/3681\/revisions"}],"predecessor-version":[{"id":5956,"href":"https:\/\/tenhosaude.com\/en\/wp-json\/wp\/v2\/posts\/3681\/revisions\/5956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tenhosaude.com\/en\/wp-json\/wp\/v2\/media\/3683"}],"wp:attachment":[{"href":"https:\/\/tenhosaude.com\/en\/wp-json\/wp\/v2\/media?parent=3681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tenhosaude.com\/en\/wp-json\/wp\/v2\/categories?post=3681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tenhosaude.com\/en\/wp-json\/wp\/v2\/tags?post=3681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}